{"id":87097,"date":"2023-06-21T09:00:53","date_gmt":"2023-06-21T07:00:53","guid":{"rendered":"https:\/\/www.wcloc.com\/comment-sont-videes-toilettes-de-chantier"},"modified":"2023-07-13T11:37:34","modified_gmt":"2023-07-13T09:37:34","slug":"comment-sont-videes-toilettes-de-chantier","status":"publish","type":"post","link":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier","title":{"rendered":"Comment sont vid\u00e9es les toilettes de chantier ?"},"content":{"rendered":"<p>Les <strong>toilettes de chantier<\/strong>, aussi nomm\u00e9es cabines sanitaires mobiles \u00e0 recirculation, sont une n\u00e9cessit\u00e9 pour les travailleurs et doivent \u00eatre vid\u00e9es r\u00e9guli\u00e8rement pour \u00e9viter les odeurs et les probl\u00e8mes d\u2019hygi\u00e8ne. Ainsi, la <strong>vidange des toilettes de chantier<\/strong> est un processus important pour assurer la propret\u00e9 sur les chantiers. WC Loc peut vous fournir des <strong>services de vidange r\u00e9guliers<\/strong> pour que vos toilettes de chantier restent propres.<\/p>\n<h2>Quelles sont les r\u00e9glementations d\u2019une toilette de chantier ?<\/h2>\n<p>Selon le Code du travail, les employeurs ont l\u2019obligation de fournir des <strong>installations sanitaires<\/strong> ad\u00e9quates pour leurs employ\u00e9s sur les chantiers de construction. Les toilettes de chantier doivent \u00eatre situ\u00e9es \u00e0 une distance raisonnable des zones de travail et doivent \u00eatre facilement accessibles. La norme AFNOR EN16194 concernant les cabines sanitaires autonomes pr\u00e9cise une distance maximale de 100m entre les WC et le poste de travail et de 2 \u00e9tages maximum. Les travailleurs doivent \u00e9galement \u00eatre inform\u00e9s de l\u2019emplacement des installation sanitaires.<\/p>\n<p>En ce qui concerne le <strong>traitement des effluents<\/strong>, WC Loc suit les r\u00e9glementations locales et nationales en mati\u00e8re de traitement des d\u00e9chets. Les effluents sont stock\u00e9s de mani\u00e8re s\u00fbre et transport\u00e9s vers des <strong>sites de traitement<\/strong> appropri\u00e9s.<\/p>\n<p>De plus, les toilettes de chantier doivent \u00eatre <strong>nettoy\u00e9es et d\u00e9sinfect\u00e9es<\/strong> une fois par semaine et nettoy\u00e9es tous les jours. Et doivent disposer en permanence de <strong>consommables disponibles<\/strong> tels que du papier toilette, du savon et des serviettes en papier.<\/p>\n<p>Louer une toilette mobile chez WC Loc, c\u2019est b\u00e9n\u00e9ficier de <strong>services de nettoyage, de d\u00e9sinfection et de r\u00e9assort en consommbales \u00e0 minima hebdomadaires<\/strong> pour maintenir les installations sanitaires en bon \u00e9tat. Cette prestation est incluse dans le tarif de location et respecte les exigences de la norme EN 16194, tant en fr\u00e9quence, qu\u2019en \u00e9cocompatibilit\u00e9 des produits sanitaires utilis\u00e9s et en d\u00e9roul\u00e9 des process d\u2019entretien.<\/p>\n<h3>Les avantages des toilettes de chantier<\/h3>\n<p>La location de <a href=\"https:\/\/www.wcloc.com\/fr\/c\/chantier-fr-lux\/toilettes-autonomes-chantier\">toilettes autonomes de chantier<\/a> pr\u00e9sente de nombreux avantages pour les entreprises de construction et leurs travailleurs :<\/p>\n<ul>\n<li><strong>Confort et hygi\u00e8ne<\/strong> : les toilettes de chantier offrent un environnement propre et hygi\u00e9nique pour les travailleurs,<\/li>\n<li><strong>Respect des r\u00e9glementations <\/strong>: en louant des toilettes de chantier, les entreprises de construction peuvent se conformer aux r\u00e9glementations locales et nationales en mati\u00e8re d\u2019installations sanitaires,<\/li>\n<li><strong>\u00c9conomie d\u2019eau<\/strong> : les toilettes de chantier sont con\u00e7ues pour une utilisation efficace de l\u2019eau, ce qui peut aider \u00e0 \u00e9conomiser de l\u2019eau et \u00e0 r\u00e9duire les co\u00fbts,<\/li>\n<li><strong>Mobilit\u00e9<\/strong> : elles sont faciles \u00e0 installer et \u00e0 d\u00e9placer selon les besoins du chantier.<\/li>\n<\/ul>\n<h2>Comment fonctionne un WC de chantier ?<\/h2>\n<p>Un WC de chantier est un <strong>syst\u00e8me autonome<\/strong> qui ne n\u00e9cessite pas de raccordement \u00e0 un r\u00e9seau d\u2019assainissement ou d\u2019eau. Il est \u00e9quip\u00e9 d\u2019un <strong>r\u00e9servoir d\u2019eau propre<\/strong> et d\u2019un <strong>r\u00e9servoir de stockage des effluents<\/strong>, qui peuvent \u00eatre vid\u00e9s \u00e0 intervalles r\u00e9guliers. Le syst\u00e8me utilise une pompe \u00e9lectrique pour aspirer les d\u00e9chets du r\u00e9servoir et les diriger vers le r\u00e9servoir de stockage.<\/p>\n<h3>Comment entretenir vos toilettes de chantier ?<\/h3>\n<p>Les toilettes de chantier sont entretenues pour am\u00e9liorer toujours plus les conditions de travail. Pour cela, un <strong>protocole complet de nettoyage<\/strong> est assur\u00e9 par WC Loc :<\/p>\n<ul>\n<li>Pulv\u00e9risation de la <strong>solution virucide et bact\u00e9ricide<\/strong> sur la porte face ext\u00e9rieure et sur les surfaces int\u00e9rieures de la cabine,<\/li>\n<li><strong>D\u00e9sinfection<\/strong> de la cuve apr\u00e8s vidange,<\/li>\n<li><strong>Nettoyage<\/strong> int\u00e9rieur et ext\u00e9rieur de la cabine,<\/li>\n<li>Remplacement du <strong>produit stabilisant<\/strong> de la cuve et des consommables,<\/li>\n<li><strong>Signature de notre passage<\/strong> avec la pulv\u00e9risation d\u2019un d\u00e9sodorisant, le remplissage de la fiche suivi hygi\u00e8ne et l\u2019envoi du SMS confirmation de prestation.<\/li>\n<\/ul>\n<h2>Comment vider un wc de chantier ?<\/h2>\n<p>La vidange d\u2019un WC de chantier doit \u00eatre effectu\u00e9e par un <strong>vidangeur agr\u00e9\u00e9<\/strong> pour des raisons de s\u00e9curit\u00e9 et de conformit\u00e9 r\u00e9glementaire. Chez WC Loc, nous sommes vidangeurs agr\u00e9\u00e9s pour les toilettes de chantier et nous pouvons garantir que <strong>les d\u00e9chets sont trait\u00e9s de mani\u00e8re responsable<\/strong> et respectueuse de l\u2019environnement.<\/p>\n<p>Lorsque nous vidons les toilettes de chantier, nous \u00e9mettons un <strong>bordereau de suivi des d\u00e9chets<\/strong>, qui permet de les tracer depuis leur origine jusqu\u2019\u00e0 leur \u00e9limination finale. Cela garantit un traitement des d\u00e9chets appropri\u00e9 et conforme aux <strong>r\u00e9glementations environnementales<\/strong> en vigueur.<\/p>\n<h3>\u00c0 quelle fr\u00e9quence la vidange est-elle effectu\u00e9e ?<\/h3>\n<p>De mani\u00e8re hebdomadaire, nous r\u00e9alisons la <strong>vidange de vos cuves<\/strong> et mat\u00e9riels le n\u00e9cessitant. Tout au long de votre location, nous effectuons <strong>une \u00e0 plusieurs fois par semaine<\/strong> le nettoyage int\u00e9gral de vos <a href=\"https:\/\/www.wcloc.com\/fr-lux\/c\/chantier-fr-lux\">sanitaires de chantier<\/a>, ainsi que le r\u00e9approvisionnement des consommables.<\/p>\n<h2>Quelles sont les \u00e9tapes d\u2019une vidange ?<\/h2>\n<p>Le processus de vidange des toilettes est relativement simple. Nous utilisons une pompe \u00e0 vide pour <strong>aspirer les d\u00e9chets<\/strong> du r\u00e9servoir de stockage dans notre camion de vidange. Les d\u00e9chets sont ensuite transport\u00e9s vers une <strong>station d\u2019\u00e9puration ou un site d\u2019\u00e9limination autoris\u00e9<\/strong> pour leur traitement et leur \u00e9limination. Chez WC Loc, nous pouvons fournir des services de vidange r\u00e9guliers pour vous aider \u00e0 maintenir les toilettes de chantier en parfait \u00e9t\u00e9 de fonctionnement.<\/p>\n<p>Lors de la vidange, un <strong>nettoyage complet des toilettes de chantier<\/strong><img decoding=\"async\" width=\"300\" height=\"276\" class=\"alignnone size-medium wp-image-85495\" src=\"https:\/\/www.wcloc.com\/wp-content\/uploads\/2023\/06\/CAB-AR-4-539x495-1-300x276.webp\" alt=\"Nettoyage des toilettes de chantier\" srcset=\"https:\/\/www.wcloc.com\/wp-content\/uploads\/2023\/06\/CAB-AR-4-539x495-1-300x276.webp 300w, https:\/\/www.wcloc.com\/wp-content\/uploads\/2023\/06\/CAB-AR-4-539x495-1-258x237.webp 258w, https:\/\/www.wcloc.com\/wp-content\/uploads\/2023\/06\/CAB-AR-4-539x495-1-98x90.webp 98w, https:\/\/www.wcloc.com\/wp-content\/uploads\/2023\/06\/CAB-AR-4-539x495-1.webp 539w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> est automatiquement effectu\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"Les toilettes de chantier, aussi nomm\u00e9es cabines sanitaires mobiles \u00e0 recirculation, sont une n\u00e9cessit\u00e9 pour les travailleurs et doivent \u00eatre vid\u00e9es r\u00e9guli\u00e8rement pour \u00e9viter les odeurs et les probl\u00e8mes d\u2019hygi\u00e8ne. Ainsi, la vidange des toilettes de chantier est un processus important pour assurer la propret\u00e9 sur les chantiers. WC Loc peut vous fournir des services [&hellip;]","protected":false},"author":50,"featured_media":87098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[762,763],"tags":[],"class_list":["post-87097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseils-fr-lux","category-hygiene-fr-lux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment sont vid\u00e9es les toilettes de chantier ? - WC Loc<\/title>\n<meta name=\"description\" content=\"Wc loc vous explique la r\u00e8glementation et le fonctionnement du nettoyage des toilettes de chantier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment sont vid\u00e9es les toilettes de chantier ? - WC Loc\" \/>\n<meta property=\"og:description\" content=\"Wc loc vous explique la r\u00e8glementation et le fonctionnement du nettoyage des toilettes de chantier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier\" \/>\n<meta property=\"og:site_name\" content=\"WC Loc\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-21T07:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-13T09:37:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wcloc.com\/wp-content\/uploads\/2022\/12\/WC-ESTANDAR-01-e1656583347333.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"599\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Helene Lemeiter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helene Lemeiter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier\"},\"author\":{\"name\":\"Helene Lemeiter\",\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux#\\\/schema\\\/person\\\/c1d3e5cca8943626b916c68e8645fb02\"},\"headline\":\"Comment sont vid\u00e9es les toilettes de chantier ?\",\"datePublished\":\"2023-06-21T07:00:53+00:00\",\"dateModified\":\"2023-07-13T09:37:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier\"},\"wordCount\":913,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wcloc.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WC-ESTANDAR-01-e1656583347333.jpg\",\"articleSection\":[\"Conseils\",\"Hygi\u00e8ne\"],\"inLanguage\":\"fr-LUX\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier\",\"url\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier\",\"name\":\"Comment sont vid\u00e9es les toilettes de chantier ? - WC Loc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wcloc.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WC-ESTANDAR-01-e1656583347333.jpg\",\"datePublished\":\"2023-06-21T07:00:53+00:00\",\"dateModified\":\"2023-07-13T09:37:34+00:00\",\"description\":\"Wc loc vous explique la r\u00e8glementation et le fonctionnement du nettoyage des toilettes de chantier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier#breadcrumb\"},\"inLanguage\":\"fr-LUX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LUX\",\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier#primaryimage\",\"url\":\"https:\\\/\\\/www.wcloc.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WC-ESTANDAR-01-e1656583347333.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wcloc.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WC-ESTANDAR-01-e1656583347333.jpg\",\"width\":599,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/comment-sont-videes-toilettes-de-chantier#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Conseils\",\"item\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\\\/category\\\/conseils-fr-lux\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment sont vid\u00e9es les toilettes de chantier ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux#website\",\"url\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\",\"name\":\"WC Loc\",\"description\":\"Un site utilisant Les sites de platform.enygea.fr\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-LUX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux#organization\",\"name\":\"WC Loc\",\"url\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LUX\",\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wcloc.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.wcloc.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo.png\",\"width\":291,\"height\":71,\"caption\":\"WC Loc\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wcloc.com\\\/fr-lux#\\\/schema\\\/person\\\/c1d3e5cca8943626b916c68e8645fb02\",\"name\":\"Helene Lemeiter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LUX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e0c00ca7328b25818d669bbe51f22033f59854e00418a9667f68b01be4e309e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e0c00ca7328b25818d669bbe51f22033f59854e00418a9667f68b01be4e309e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e0c00ca7328b25818d669bbe51f22033f59854e00418a9667f68b01be4e309e?s=96&d=mm&r=g\",\"caption\":\"Helene Lemeiter\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment sont vid\u00e9es les toilettes de chantier ? - WC Loc","description":"Wc loc vous explique la r\u00e8glementation et le fonctionnement du nettoyage des toilettes de chantier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier","og_locale":"fr_FR","og_type":"article","og_title":"Comment sont vid\u00e9es les toilettes de chantier ? - WC Loc","og_description":"Wc loc vous explique la r\u00e8glementation et le fonctionnement du nettoyage des toilettes de chantier.","og_url":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier","og_site_name":"WC Loc","article_published_time":"2023-06-21T07:00:53+00:00","article_modified_time":"2023-07-13T09:37:34+00:00","og_image":[{"width":599,"height":599,"url":"https:\/\/www.wcloc.com\/wp-content\/uploads\/2022\/12\/WC-ESTANDAR-01-e1656583347333.jpg","type":"image\/jpeg"}],"author":"Helene Lemeiter","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Helene Lemeiter","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier#article","isPartOf":{"@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier"},"author":{"name":"Helene Lemeiter","@id":"https:\/\/www.wcloc.com\/fr-lux#\/schema\/person\/c1d3e5cca8943626b916c68e8645fb02"},"headline":"Comment sont vid\u00e9es les toilettes de chantier ?","datePublished":"2023-06-21T07:00:53+00:00","dateModified":"2023-07-13T09:37:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier"},"wordCount":913,"publisher":{"@id":"https:\/\/www.wcloc.com\/fr-lux#organization"},"image":{"@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier#primaryimage"},"thumbnailUrl":"https:\/\/www.wcloc.com\/wp-content\/uploads\/2022\/12\/WC-ESTANDAR-01-e1656583347333.jpg","articleSection":["Conseils","Hygi\u00e8ne"],"inLanguage":"fr-LUX"},{"@type":"WebPage","@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier","url":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier","name":"Comment sont vid\u00e9es les toilettes de chantier ? - WC Loc","isPartOf":{"@id":"https:\/\/www.wcloc.com\/fr-lux#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier#primaryimage"},"image":{"@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier#primaryimage"},"thumbnailUrl":"https:\/\/www.wcloc.com\/wp-content\/uploads\/2022\/12\/WC-ESTANDAR-01-e1656583347333.jpg","datePublished":"2023-06-21T07:00:53+00:00","dateModified":"2023-07-13T09:37:34+00:00","description":"Wc loc vous explique la r\u00e8glementation et le fonctionnement du nettoyage des toilettes de chantier.","breadcrumb":{"@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier#breadcrumb"},"inLanguage":"fr-LUX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier"]}]},{"@type":"ImageObject","inLanguage":"fr-LUX","@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier#primaryimage","url":"https:\/\/www.wcloc.com\/wp-content\/uploads\/2022\/12\/WC-ESTANDAR-01-e1656583347333.jpg","contentUrl":"https:\/\/www.wcloc.com\/wp-content\/uploads\/2022\/12\/WC-ESTANDAR-01-e1656583347333.jpg","width":599,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/www.wcloc.com\/fr-lux\/comment-sont-videes-toilettes-de-chantier#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Conseils","item":"https:\/\/www.wcloc.com\/fr-lux\/category\/conseils-fr-lux"},{"@type":"ListItem","position":2,"name":"Comment sont vid\u00e9es les toilettes de chantier ?"}]},{"@type":"WebSite","@id":"https:\/\/www.wcloc.com\/fr-lux#website","url":"https:\/\/www.wcloc.com\/fr-lux","name":"WC Loc","description":"Un site utilisant Les sites de platform.enygea.fr","publisher":{"@id":"https:\/\/www.wcloc.com\/fr-lux#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wcloc.com\/fr-lux?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-LUX"},{"@type":"Organization","@id":"https:\/\/www.wcloc.com\/fr-lux#organization","name":"WC Loc","url":"https:\/\/www.wcloc.com\/fr-lux","logo":{"@type":"ImageObject","inLanguage":"fr-LUX","@id":"https:\/\/www.wcloc.com\/fr-lux#\/schema\/logo\/image\/","url":"https:\/\/www.wcloc.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/www.wcloc.com\/wp-content\/uploads\/2023\/04\/logo.png","width":291,"height":71,"caption":"WC Loc"},"image":{"@id":"https:\/\/www.wcloc.com\/fr-lux#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.wcloc.com\/fr-lux#\/schema\/person\/c1d3e5cca8943626b916c68e8645fb02","name":"Helene Lemeiter","image":{"@type":"ImageObject","inLanguage":"fr-LUX","@id":"https:\/\/secure.gravatar.com\/avatar\/9e0c00ca7328b25818d669bbe51f22033f59854e00418a9667f68b01be4e309e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9e0c00ca7328b25818d669bbe51f22033f59854e00418a9667f68b01be4e309e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e0c00ca7328b25818d669bbe51f22033f59854e00418a9667f68b01be4e309e?s=96&d=mm&r=g","caption":"Helene Lemeiter"}}]}},"_links":{"self":[{"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/posts\/87097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/comments?post=87097"}],"version-history":[{"count":2,"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/posts\/87097\/revisions"}],"predecessor-version":[{"id":90370,"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/posts\/87097\/revisions\/90370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/media\/87098"}],"wp:attachment":[{"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/media?parent=87097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/categories?post=87097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wcloc.com\/fr-lux\/wp-json\/wp\/v2\/tags?post=87097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}